{"id":1057,"date":"2013-09-16T12:14:11","date_gmt":"2013-09-16T10:14:11","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=1057"},"modified":"2013-09-16T12:14:11","modified_gmt":"2013-09-16T10:14:11","slug":"laureati-trovano-lavoro","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/","title":{"rendered":"I laureati trovano lavoro: lo dicono i numeri"},"content":{"rendered":"<p>I <strong>laureati trovano lavoro<\/strong> pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.<\/p>\n<p>E viene costantemente smentito dai numeri. Dati che parlano chiaro, ad esempio, sono quelli pubblicati sul quotidiano La Stampa: la richiesta di laureati \u00e8 in costante aumento, le assunzioni riservate a chi ha raggiunto questo tanto agognato titolo di studio sono salite rispetto a dodici mesi fa di oltre quindici punti percentuali.<\/p>\n<p>Dall&#8217;ultima analisi effettuata da Excelsion Unioncamere, si evince che tra i neolaureati i pi\u00f9 richiesti sono quelli in possesso di una laurea in economia, seguiti dagli ingegneri, ma si affacciano sul mercato del lavoro con ottime possibilit\u00e0 di trovare occupazione anche i laureati in giurisprudenza e scienze politiche.<\/p>\n<p>Tutto bene? Insomma. Secondo le imprese, quattro assunti su cinque, tra i neolaureati, hanno bisogno di ulteriore formazione, una volta giunti in azienda.<\/p>\n<p>Questo accade, per\u00f2, perch\u00e9 non tutte le universit\u00e0 educano il proprio iscritto alle professioni che avr\u00e0 poi modo di praticare. Cosa che accade, invece, all&#8217;Universit\u00e0 Niccol\u00f2 Cusano, realt\u00e0 in cui ognuno viene preso per mano e accompagnato dal momento dell&#8217;immatricolazione al momento dell&#8217;ingresso nel mondo del lavoro.<\/p>\n<p>Realt\u00e0 in cui ogni studente, alla fine del proprio percorso formativo, riesce, grazie alle innovative metodologie di insegnamento di cui l&#8217;Universit\u00e0 Niccol\u00f2 Cusano dispone, a padroneggiare tutto quello che ha avuto modo di apprendere nel corso degli anni, \u00a0accompagnato ormai da un metodo che sar\u00e0 suo per la vita e che gli servir\u00e0, dunque, anche e soprattutto nel mondo del lavoro.<\/p>\n<p>Perch\u00e9 gli esami non finiscono mai, questo s\u00ec, ma \u00e8 anche vero che, una volta capito come si fa a superarli, fanno decisamente un po&#8217; meno paura.<\/p>\n<p><a title=\"Universit\u00e0 Niccol\u00f2 Cusano: clicca qui per avere maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\" target=\"_blank\">Per avere maggiori informazioni sull&#8217;Universit\u00e0 Niccol\u00f2 Cusano, clicca qui\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice...","protected":false},"author":5,"featured_media":1058,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[173],"class_list":["post-1057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-universita-niccolo-cusano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con la laurea non si trova lavoro? Balle, lo dicono i numeri<\/title>\n<meta name=\"description\" content=\"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con la laurea non si trova lavoro? Balle, lo dicono i numeri\" \/>\n<meta property=\"og:description\" content=\"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-09-16T10:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"232\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Arduini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Arduini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/\"},\"author\":{\"name\":\"Roberto Arduini\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\"},\"headline\":\"I laureati trovano lavoro: lo dicono i numeri\",\"datePublished\":\"2013-09-16T10:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/laurea12.jpg\",\"keywords\":[\"universit\u00e0 niccol\u00f2 cusano\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/\",\"name\":\"Con la laurea non si trova lavoro? Balle, lo dicono i numeri\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/laurea12.jpg\",\"datePublished\":\"2013-09-16T10:14:11+00:00\",\"description\":\"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/laurea12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/09\\\/laurea12.jpg\",\"width\":360,\"height\":232,\"caption\":\"Prendere la laurea per poi tuffarsi nel mondo del lavoro: all'Universit\u00e0 Niccol\u00f2 Cusano \u00e8 possibile farlo da protagonisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-trovano-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I laureati trovano lavoro: lo dicono i numeri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\",\"name\":\"Roberto Arduini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"caption\":\"Roberto Arduini\"},\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con la laurea non si trova lavoro? Balle, lo dicono i numeri","description":"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"Con la laurea non si trova lavoro? Balle, lo dicono i numeri","og_description":"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2013-09-16T10:14:11+00:00","og_image":[{"width":360,"height":232,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg","type":"image\/jpeg"}],"author":"Roberto Arduini","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"Roberto Arduini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/"},"author":{"name":"Roberto Arduini","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c"},"headline":"I laureati trovano lavoro: lo dicono i numeri","datePublished":"2013-09-16T10:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg","keywords":["universit\u00e0 niccol\u00f2 cusano"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/","name":"Con la laurea non si trova lavoro? Balle, lo dicono i numeri","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg","datePublished":"2013-09-16T10:14:11+00:00","description":"I laureati trovano lavoro pi\u00f9 facilmente degli altri. Chi dice il contrario palesa ignoranza o, nel caso peggiore delle ipotesi, malafede.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/09\/laurea12.jpg","width":360,"height":232,"caption":"Prendere la laurea per poi tuffarsi nel mondo del lavoro: all'Universit\u00e0 Niccol\u00f2 Cusano \u00e8 possibile farlo da protagonisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-trovano-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"I laureati trovano lavoro: lo dicono i numeri"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c","name":"Roberto Arduini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","caption":"Roberto Arduini"},"url":"https:\/\/www.unicusano.it\/blog\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/1057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=1057"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/1057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/1058"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=1057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=1057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=1057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}