{"id":1699,"date":"2013-10-23T11:15:21","date_gmt":"2013-10-23T09:15:21","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=1699"},"modified":"2013-10-23T11:16:03","modified_gmt":"2013-10-23T09:16:03","slug":"laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/","title":{"rendered":"Laureati nell&#8217;Universit\u00e0 telematica che ti permette di seguire le lezioni anche in presenza"},"content":{"rendered":"<p>Rispetto alle\u00a0<b>universit\u00e0 pubbliche<\/b>, che segnano un -17 per cento delle\u00a0<b>immatricolazioni<\/b>, il numero di iscritti agli\u00a0<b>atenei\u00a0<i>on line<\/i><\/b>\u00a0\u00e8 in continua espansione da dieci anni a questa parte.<\/p>\n<p>Anzi, pi\u00f9 che di espansione, guardando i numeri, si potrebbe parlare di vero e proprio boom: il numero di persone che vogliono prendere una laurea studiando tramite internet \u00e8 passato dai\u00a0<b>1.500\u00a0<\/b>del 2003 ai\u00a0<b>39.792\u00a0<\/b>del 2013, con un aumento medio annuo del<b>\u00a016 per cento<\/b>.<\/p>\n<p>E quelli che frequentano\u00a0<b>l\u2019universit\u00e0 telematica ormai rappresentano il 2 per cento del totale. <\/b>E&#8217; questo quanto emerge da una analisi\u00a0portata avanti dalla migliore Universit\u00e0 Telematica Italiana, \u00a0<b>l\u2019Universit\u00e0 \u201cNiccol\u00f2 Cusano\u201d di Roma<\/b>, fondata nel 2006 e oggi al primo posto fra le strutture riconosciute dal\u00a0<b>Miur<\/b>\u00a0per numero di laureati e attivit\u00e0 didattiche.\u00a0La crescita continua del numero di iscritti agli\u00a0<b>atenei\u00a0<i>on line<\/i><\/b>\u00a0\u00e8 ascrivibile a diversi fattori, che poi sono i punti forza dell\u2019insegnamento a distanza: in due parole,\u00a0<b>risparmio<\/b>\u00a0e\u00a0<b>praticit\u00e0.<\/b><\/p>\n<p>Perch\u00e9 sempre pi\u00f9 persone scelgono di affidare il proprio percorso accademico ad una universit\u00e0 telematica? I fattori sono molteplici: \u00a0l\u2019insegnamento a distanza riesce a facilitare chi di andare a seguire lezioni in sede non ha la possibilit\u00e0, come i\u00a0<b>lavoratori<\/b>\u00a0il desiderio di conseguire un titolo di studio pi\u00f9 elevato o i giovani che non possono permettersi di trasferirsi lontano da casa per gli alti costi che comporta la vita da\u00a0<b>fuori sede<\/b>. Dal punto di vista\u00a0<b>didattico<\/b>, poi, gli\u00a0<b>atenei\u00a0<i>on line<\/i><\/b>\u00a0propongono ormai una\u00a0<b>vasta offerta<\/b>, cosa che contribuisce ad attrarre sempre pi\u00f9 iscritti.<\/p>\n<p>Cos&#8217;\u00e8 che rende davvero unica l&#8217;<strong>Universit\u00e0 Niccol\u00f2 Cusano<\/strong>? La grandissima offerta formativa proposta. Il fatto che ogni studente sia seguito dal momento dell&#8217;immatricolazione fino al conseguimento della laurea da un consulente didattico che lo prende per mano e che lo accompagna passo dopo passo fino al traguardo. La possibilit\u00e0 di seguire le lezioni sia in videoconferenza che tramite la piattaforma e-learning ma anche \u00a0in presenza, presso il fantastico campus in stile americano che si trova nel cuore di Roma o nelle altre sessanta strutture che sono capillarmente disposte nel territorio nazionale. \u00a0Una realt\u00e0 creata davvero su misura per ogni tipo di studente. L&#8217;Universit\u00e0 del presente e del futuro.<\/p>\n<p><strong><a title=\"Unicusano, la migliore universit\u00e0 italiana: per avere maggiori informazioni, clicca qui \" href=\"https:\/\/www.unicusano.it\/contatti-universita\" target=\"_blank\">https:\/\/www.unicusano.it\/contatti-universita<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rispetto alle\u00a0universit\u00e0 pubbliche, che segnano un -17 per cento...","protected":false},"author":5,"featured_media":781,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[229,180],"class_list":["post-1699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-laurea-internet","tag-universita-telematiche"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza<\/title>\n<meta name=\"description\" content=\"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza\" \/>\n<meta property=\"og:description\" content=\"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-23T09:15:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-10-23T09:16:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Arduini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Arduini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/\"},\"author\":{\"name\":\"Roberto Arduini\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\"},\"headline\":\"Laureati nell&#8217;Universit\u00e0 telematica che ti permette di seguire le lezioni anche in presenza\",\"datePublished\":\"2013-10-23T09:15:21+00:00\",\"dateModified\":\"2013-10-23T09:16:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/\"},\"wordCount\":382,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/crescita-universit\u00e0-telematiche.jpg\",\"keywords\":[\"laurea internet\",\"universit\u00e0 telematiche\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/\",\"name\":\"L'Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/crescita-universit\u00e0-telematiche.jpg\",\"datePublished\":\"2013-10-23T09:15:21+00:00\",\"dateModified\":\"2013-10-23T09:16:03+00:00\",\"description\":\"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/crescita-universit\u00e0-telematiche.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/06\\\/crescita-universit\u00e0-telematiche.jpg\",\"width\":390,\"height\":259,\"caption\":\"Crescita universit\u00e0 telematiche\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laureati nell&#8217;Universit\u00e0 telematica che ti permette di seguire le lezioni anche in presenza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\",\"name\":\"Roberto Arduini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"caption\":\"Roberto Arduini\"},\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza","description":"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/","og_locale":"it_IT","og_type":"article","og_title":"L'Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza","og_description":"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2013-10-23T09:15:21+00:00","article_modified_time":"2013-10-23T09:16:03+00:00","og_image":[{"width":390,"height":259,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg","type":"image\/jpeg"}],"author":"Roberto Arduini","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"Roberto Arduini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/"},"author":{"name":"Roberto Arduini","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c"},"headline":"Laureati nell&#8217;Universit\u00e0 telematica che ti permette di seguire le lezioni anche in presenza","datePublished":"2013-10-23T09:15:21+00:00","dateModified":"2013-10-23T09:16:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/"},"wordCount":382,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg","keywords":["laurea internet","universit\u00e0 telematiche"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/","name":"L'Universit\u00e0 ideale? Questa: puoi studiare su internet e in presenza","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg","datePublished":"2013-10-23T09:15:21+00:00","dateModified":"2013-10-23T09:16:03+00:00","description":"Rispetto alle universit\u00e0 pubbliche, che segnano un -17 per cento delle immatricolazioni, il numero di iscritti agli atenei on line \u00e8 in continua espansione da dieci anni a questa parte.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/06\/crescita-universit\u00e0-telematiche.jpg","width":390,"height":259,"caption":"Crescita universit\u00e0 telematiche"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laureati-nelluniversita-telematica-che-ti-permette-di-seguire-le-lezioni-anche-in-presenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Laureati nell&#8217;Universit\u00e0 telematica che ti permette di seguire le lezioni anche in presenza"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c","name":"Roberto Arduini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","caption":"Roberto Arduini"},"url":"https:\/\/www.unicusano.it\/blog\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/1699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=1699"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/1699\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/781"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=1699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=1699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=1699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}