{"id":2380,"date":"2013-11-29T07:05:46","date_gmt":"2013-11-29T06:05:46","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=2380"},"modified":"2013-11-30T07:21:58","modified_gmt":"2013-11-30T06:21:58","slug":"lunicusano-protagonista-di-young-orienta-il-tuo-futuro","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/","title":{"rendered":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">L\u2019Universit\u00e0 Niccol\u00f2 Cusano, recependo l\u2019interesse nei suoi confronti proveniente dagli studenti del Nord Italia, partecipa alla 6^ edizione\u00a0di \u201cYoung \u2013 Orienta il tuo futuro\u201d, uno\u00a0stimolante appuntamento dedicato all\u2019orientamento scuola, formazione, universit\u00e0 e lavoro, in corso fino al 30 novembre ad Erba.<\/p>\n<p style=\"text-align: left;\">Un evento in grande crescita, pensato e voluto per le nuove generazioni, che nella scorsa\u00a0edizione ha registrato la\u00a0visita di oltre 15.000 tra ragazzi e famiglie provenienti dalle province di Como,\u00a0Lecco, Monza e Brianza, Milano, Varese, Sondrio, Bergamo, classi da\u00a0160 scuole,\u00a0150 realt\u00e0 in\u00a0esposizione, pi\u00f9 di\u00a0100 eventi di orientamento.<\/p>\n<p style=\"text-align: left;\">YOUNG\u00a0\u00a0informa,\u00a0orienta\u00a0e\u00a0accompagna\u00a0i ragazzi nel difficile e delicato momento della scelta formativa e professionale, presentandosi come una piattaforma di scambio tra domanda e offerta in campo scolastico e lavorativo.<\/p>\n<p style=\"text-align: left;\">I ragazzi delle\u00a0scuole secondarie di secondo livello e le loro famiglie potranno cos\u00ec entrare a contatto diretto con la realt\u00e0 dell\u2019Unicusano, un\u2019universit\u00e0 telematica e in presenza, capace di abbinare l\u2019innovazione tecnologica alla migliore tradizione accademica italiana.<\/p>\n<p style=\"text-align: left;\">Il campus dell&#8217;Universit\u00e0 Niccol\u00f2 Cusano, disegnato sul modello anglosassone, offre con la sua struttura di 16 mila metri quadri a Roma uno spazio ideale per lo studio e l&#8217;attivit\u00e0 di ricerca scientifica. Tra aule multimediali, biblioteca, sale lettura e centri di ricerca, oltre a spazi ricreativi come mensa, bar, palestra e una foresteria per i fuori sede, l\u2019Unicusano \u00e8 in grado proporre ai propri studenti un percorso accademico completo sotto ogni punto di vista. Per questo, pur trattandosi di una realt\u00e0 relativamente nuova nel panorama delle universit\u00e0 italiane, l\u2019Unicusano, forte della qualit\u00e0 della propria offerta, ha gi\u00e0 riscosso in brevissimo tempo importanti successi e superato la tradizionale diffidenza, tutta italiana, che ruota intorno all\u2019istruzione privata.<\/p>\n<p style=\"text-align: left;\">\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Universit\u00e0 Niccol\u00f2 Cusano, recependo l\u2019interesse nei suoi...","protected":false},"author":5,"featured_media":2400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[243,1723],"class_list":["post-2380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento","tag-universita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"og:description\" content=\"L\u2019Universit\u00e0 Niccol\u00f2 Cusano, recependo l\u2019interesse nei suoi confronti proveniente dagli studenti del Nord Italia, partecipa alla 6^ edizione\u00a0di \u201cYoung \u2013 Orienta il tuo futuro\u201d, uno\u00a0stimolante appuntamento dedicato all\u2019orientamento scuola, formazione, universit\u00e0 e lavoro, in corso fino al 30 novembre ad Erba. Un evento in grande crescita, pensato e voluto per le nuove generazioni, che nella...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-29T06:05:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-11-30T06:21:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Arduini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Arduini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/\"},\"author\":{\"name\":\"Roberto Arduini\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\"},\"headline\":\"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d\",\"datePublished\":\"2013-11-29T06:05:46+00:00\",\"dateModified\":\"2013-11-30T06:21:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/\"},\"wordCount\":292,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/DSC_0113-scaled.jpg\",\"keywords\":[\"orientamento\",\"universit\u00e0\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/\",\"name\":\"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/DSC_0113-scaled.jpg\",\"datePublished\":\"2013-11-29T06:05:46+00:00\",\"dateModified\":\"2013-11-30T06:21:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/DSC_0113-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/DSC_0113-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\",\"name\":\"Roberto Arduini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"caption\":\"Roberto Arduini\"},\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","og_description":"L\u2019Universit\u00e0 Niccol\u00f2 Cusano, recependo l\u2019interesse nei suoi confronti proveniente dagli studenti del Nord Italia, partecipa alla 6^ edizione\u00a0di \u201cYoung \u2013 Orienta il tuo futuro\u201d, uno\u00a0stimolante appuntamento dedicato all\u2019orientamento scuola, formazione, universit\u00e0 e lavoro, in corso fino al 30 novembre ad Erba. Un evento in grande crescita, pensato e voluto per le nuove generazioni, che nella...","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2013-11-29T06:05:46+00:00","article_modified_time":"2013-11-30T06:21:58+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg","type":"image\/jpeg"}],"author":"Roberto Arduini","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"Roberto Arduini","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/"},"author":{"name":"Roberto Arduini","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c"},"headline":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d","datePublished":"2013-11-29T06:05:46+00:00","dateModified":"2013-11-30T06:21:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/"},"wordCount":292,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg","keywords":["orientamento","universit\u00e0"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/","name":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d - Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg","datePublished":"2013-11-29T06:05:46+00:00","dateModified":"2013-11-30T06:21:58+00:00","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2013\/11\/DSC_0113-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/lunicusano-protagonista-di-young-orienta-il-tuo-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"L\u2019Unicusano protagonista di \u201cYoung \u2013 Orienta il tuo futuro\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c","name":"Roberto Arduini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","caption":"Roberto Arduini"},"url":"https:\/\/www.unicusano.it\/blog\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/2380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=2380"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/2380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/2400"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=2380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=2380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=2380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}