{"id":3816,"date":"2014-02-25T11:00:26","date_gmt":"2014-02-25T10:00:26","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=3816"},"modified":"2014-02-25T11:01:11","modified_gmt":"2014-02-25T10:01:11","slug":"laurea-carcere-scienze-politiche","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/","title":{"rendered":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano e il sole della cultura che arriva oltre le sbarre"},"content":{"rendered":"<p>Grazie <a title=\"I corsi di Laurea dell'Universit\u00e0 Niccol\u00f2 Cusano: scegli la tua strada\" href=\"https:\/\/www.unicusano.it\/universita\/corsi-di-laurea\" target=\"_blank\">all&#8217;<strong>Universit\u00e0 Niccol\u00f2<\/strong> <strong>Cusano<\/strong><\/a> il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi. Ed ha consentito ad uno studente di laurearsi in carcere, \u00a0a Santa Maria Capua Vetere, con la commissione universitaria che per la discussione della tesi si \u00e8 recata dietro le sbarre.<\/p>\n<p>Il neo dottore ha discusso la propria tesi di laurea in <strong>Storia delle Dottrine Politiche<\/strong> dal titolo \u00ab<em><strong>La riforma protestante e la vita politica<\/strong><\/em>\u00bb, di fronte alla Commissione inviata dall&#8217;Universit\u00e0 Niccol\u00f2 Cusano nel carcere campano e formata dalla<strong> Preside di Scienze Politiche dell&#8217;Unicusano,<\/strong> Maria Paola Pagnini, dal suo relatore, Alberto Clerici (Storia delle Dottrine Politiche), Silvio Berardi (Storia Contemporanea) e Alfonso Giordano.<\/p>\n<p>Una dimostrazione importante di come si debba pretendere <strong>il diritto allo studio<\/strong> anche nei momenti pi\u00f9 complicati. Perch\u00e9 per iniziare a rifarsi una vita, per cercare di limare i problemi del passato, accrescere la propria cultura, migliorare la propria persona con il conseguimento di una Laurea, pu\u00f2 essere un passo decisivo.<\/p>\n<p><strong>\u00a0Charles-Louis de Secondat,<\/strong>\u00a0barone de<strong> La Br\u00e8de e di Montesquieu<\/strong>, meglio noto unicamente come\u00a0Montesquieu, pensatore, filosofo e politico francese, ha scritto: \u201c<em>Lo studio \u00e8 sempre stato per me il rimedio sovrano contro il disgusto della vita, e non ho mai provato un dolore che un\u2019ora di lettura non sia riuscita a far svanire<\/em>.\u201d<\/p>\n<p>Impossibile contraddirlo.\u00a0Studiare allunga e \u201callarga\u201d l&#8217;esistenza. E la facolt\u00e0 di apprendere, di conoscere, di capire, di \u201ccrescere\u201d\u00a0deve essere alla portata di tutti.<\/p>\n<p>Purtroppo come evidenzia una inchiesta di\u00a0<strong><a title=\"Avvenire: studiare in carcere per tanti resta un sogno \" href=\"http:\/\/www.avvenire.it\/Cronaca\/Pagine\/studiare-in-carcere-per-tanti-resta-un-sogno.aspx\">Avvenire<\/a>,<\/strong> le statistiche del\u00a0<strong><a title=\"Ministero della Giustizia: sito web ufficiale \" href=\"https:\/\/www.giustizia.it\/giustizia\/\">Ministero della Giustizia<\/a><\/strong>\u00a0parlano chiaro. E\u00a0dicono che su 66.028 detenuti totali (38.795 italiani e 23.233 stranieri),\u00a0il 7% \u00e8 analfabeta\u00a0o privo di titolo di studio,\u00a0il 21,1% ha la licenza elementare, il 59,4% il diploma di scuola media, l\u20191,2% il diploma di scuola professionale, il 9,3% quello di scuola superiore e l\u20191,6% \u00e8 laureato.<\/p>\n<p>A proposito delle difficolt\u00e0 che incontrano i detenuti che avrebbero voglia di iniziare o riprendere gli studi, ha scritto anche\u00a0<strong><a title=\"Vietato studiare in carcere\" href=\"http:\/\/ricerca.repubblica.it\/repubblica\/archivio\/repubblica\/2002\/10\/15\/vietato-studiare-in-carcere.html\">La Repubblica<\/a><\/strong>, evidenziando come in alcune prigioni studiare possa sembrare paradossalmente \u201cvietato\u201d.<\/p>\n<p>Eppure, di\u00a0detenuti che tornano sui libri\u00a0per conquistarsi un momento di libert\u00e0 e per costruirsi un futuro migliore ce ne sono. \u00a0Lo studente che ha appena conseguito all&#8217;<strong>Universit\u00e0 Niccol\u00f2 Cusano<\/strong> una Laurea in Scienze Politiche ne \u00e8 l&#8217;esempio.<\/p>\n<p>Studiare sempre. Studiare comunque. In ogni situazione. Anche in carcere. Si pu\u00f2. Si deve. A maggior ragione se si pensa che negli ultimi anni la tecnologia ha compiuto eccezionali passi in avanti e ha sdoganato la\u00a0<strong><a title=\"Tutti i Corsi di Laurea a distanza dell'Universit\u00e0 Niccol\u00f2 Cusano\" href=\"https:\/\/www.unicusano.it\/blog\/didattica\/corsi\/corsi_di_laurea_a_distanza\/#.UtJcPtLuKSo\">formazione universitaria a distanza<\/a><\/strong>.<\/p>\n<p>Esistono\u00a0atenei d\u2019eccellenza\u00a0che offrono la possibilit\u00e0 di\u00a0studiare online\u00a0attraverso metodologie d\u2019insegnamento all\u2019avanguardia che mettono a disposizione dello studente non solo tutto il materiale didattico necessario al superamento di un esame, ma anche\u00a0la possibilit\u00e0 di dialogare con i docenti, con colleghi universitari o con tutor di facolt\u00e0.<\/p>\n<p>Kahlil Gibran ha scritto: \u201c<em>L\u2019errore spesso rappresenta l\u2019inizio della conoscenza<\/em>\u201c. \u00a0E\u2019 giusto dare a chi ha sbagliato tutti gli strumenti in grado di portarlo, in futuro, a non prendere lo stesso abbaglio. Lo studio pu\u00f2 e deve rappresentare, in alcuni casi, il primo passo da compiere per combattere la recidivit\u00e0 cui troppo spesso vanno incontro alcuni detenuti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grazie all&#8217;Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura...","protected":false},"author":5,"featured_media":3817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-3816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera<\/title>\n<meta name=\"description\" content=\"Grazie all&#039;Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera\" \/>\n<meta property=\"og:description\" content=\"Grazie all&#039;Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-25T10:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-02-25T10:01:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"195\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Arduini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Arduini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/\"},\"author\":{\"name\":\"Roberto Arduini\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\"},\"headline\":\"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano e il sole della cultura che arriva oltre le sbarre\",\"datePublished\":\"2014-02-25T10:00:26+00:00\",\"dateModified\":\"2014-02-25T10:01:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/\"},\"wordCount\":544,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/sole.jpg\",\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/\",\"name\":\"L'Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/sole.jpg\",\"datePublished\":\"2014-02-25T10:00:26+00:00\",\"dateModified\":\"2014-02-25T10:01:11+00:00\",\"description\":\"Grazie all'Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/sole.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/sole.jpg\",\"width\":259,\"height\":195,\"caption\":\"Scienze politiche, studente si laurea in carcere\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/laurea-carcere-scienze-politiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano e il sole della cultura che arriva oltre le sbarre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\",\"name\":\"Roberto Arduini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"caption\":\"Roberto Arduini\"},\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera","description":"Grazie all'Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/","og_locale":"it_IT","og_type":"article","og_title":"L'Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera","og_description":"Grazie all'Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-02-25T10:00:26+00:00","article_modified_time":"2014-02-25T10:01:11+00:00","og_image":[{"width":259,"height":195,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg","type":"image\/jpeg"}],"author":"Roberto Arduini","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"Roberto Arduini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/"},"author":{"name":"Roberto Arduini","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c"},"headline":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano e il sole della cultura che arriva oltre le sbarre","datePublished":"2014-02-25T10:00:26+00:00","dateModified":"2014-02-25T10:01:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/"},"wordCount":544,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg","articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/","name":"L'Universit\u00e0 Niccol\u00f2 Cusano e quel sole della cultura che sovrasta ogni barriera","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg","datePublished":"2014-02-25T10:00:26+00:00","dateModified":"2014-02-25T10:01:11+00:00","description":"Grazie all'Universit\u00e0 Niccol\u00f2 Cusano il sole della cultura ha oltrepassato le sbarre. La conoscenza ha superato le barriere. La cultura ha sconfitto i pregiudizi.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/02\/sole.jpg","width":259,"height":195,"caption":"Scienze politiche, studente si laurea in carcere"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/laurea-carcere-scienze-politiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano e il sole della cultura che arriva oltre le sbarre"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c","name":"Roberto Arduini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","caption":"Roberto Arduini"},"url":"https:\/\/www.unicusano.it\/blog\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/3816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=3816"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/3816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/3817"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=3816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=3816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=3816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}