{"id":4154,"date":"2014-04-01T06:00:34","date_gmt":"2014-04-01T04:00:34","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=4154"},"modified":"2017-04-11T16:48:30","modified_gmt":"2017-04-11T14:48:30","slug":"servizio-bibliotecario-nazionale","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/","title":{"rendered":"Il Servizio Bibliotecario Nazionale? Consigliato dall\u2019UniCusano"},"content":{"rendered":"<p><b>Se state studiando per prepararvi ad un esame o, ancora pi\u00f9 verosimilmente, state scrivendo una tesi di laurea, ogni consiglio utile sar\u00e0 ben accetto. Lo sa bene l\u2019UniCusano che sottolinea l\u2019importanza del Servizio Bibliotecario Nazionale. Secondo l\u2019ateneo, che ha sempre l\u2019interesse dello studente al centro del suo operato, si tratta infatti di uno strumento molto utile per raccogliere informazioni, dati e fonti con una grande qualit\u00e0 e certezza. Se siete alle prese col passaggio finale della vostra carriera accademica e avete bisogno di una mano per la bibliografia, continuate a leggere per saperne dio pi\u00f9 sul Servizio Bibliotecario Nazionale.<!--more--><\/b><\/p>\n<p>Chi ha a cuore il destino degli studenti \u00e8 consapevole di quanto sia ben accetto ogni piccolo aiuto. E cos\u00ec l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0d\u00e0 una metaforica pacca sulla spalla a tutti i ragazzi che stanno scrivendo una tesi invitandoli ad usare lo strumento del <a href=\"http:\/\/www.sbn.it\/opacsbn\/opac\/iccu\/free.jsp\" target=\"_blank\"><b>Servizio Bibliotecario Nazionale<\/b> (SBN)<\/a>. Di cosa si tratta? Tecnicamente \u00e8 la rete delle biblioteche italiane promossa dal <a href=\"http:\/\/www.beniculturali.it\/mibac\/export\/MiBAC\/index.html#&amp;panel1-1\" target=\"_blank\">MiBAC<\/a>,dalle Regioni e dalle universit\u00e0 ed \u00e8 coordinata dall\u2019<a href=\"http:\/\/www.iccu.sbn.it\/opencms\/opencms\/it\/\" target=\"_blank\">ICCU<\/a>. Al <a href=\"http:\/\/www.sbn.it\/opacsbn\/opac\/iccu\/free.jsp\" target=\"_blank\"><b>Servizio Bibliotecario Nazionale<\/b>\u00a0(SBN)<\/a>\u00a0vi aderiscono attualmente oltre 3200 biblioteche, statali, di enti locali, universitarie, di istituzioni pubbliche e private, operanti in diversi settori disciplinari. \u2028Pi\u00f9 nello specifico,\u2028il catalogo collettivo del <a href=\"http:\/\/www.sbn.it\/opacsbn\/opac\/iccu\/free.jsp\" target=\"_blank\"><b>Servizio Bibliotecario Nazionale<\/b>\u00a0(SBN)<\/a>\u00a0contiene:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 descrizioni di documenti acquisiti dalle biblioteche SBN a partire dagli anni intorno al 1990 o dall&#8217;entrata in SBN delle singole biblioteche;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 descrizioni &#8220;libro in mano&#8221; di documenti dei secoli XVI \u2013 XX;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 descrizioni recuperate dai cataloghi cartacei antecedenti al 1990.<\/p>\n<p>Va detto che la base dati dell&#8217;OPAC SBN si aggiorna settimanalmente e, soprattutto che tramite l&#8217;OPAC SBN \u00e8 possibile:<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 identificare i documenti di interesse;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 individuare le biblioteche che possiedono tali documenti ed accedere alla scheda anagrafica della singola biblioteca;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 accedere ai cataloghi locali per informazioni aggiuntive sulla disponibilit\u00e0 del documento;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 accedere al servizio in linea di prestito da remoto o fornitura di documenti in riproduzione (<a href=\"http:\/\/www.iccu.sbn.it\/genera.jsp?s=119&amp;l=it\"><span style=\"text-decoration: underline;\">ILL SBN<\/span><\/a>) se la biblioteca partecipa a tale servizio;<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 accedere alle <a href=\"http:\/\/www.iccu.sbn.it\/genera.jsp?id=164&amp;l=it\"><span style=\"text-decoration: underline;\">&#8220;Voci d&#8217;autorit\u00e0&#8221;<\/span><\/a>, voci controllate finalizzate a garantire l&#8217;univocit\u00e0 di alcuni punti di accesso del catalogo; attualmente sono presenti e ricercabili le schede relative ad una porzione dell&#8217;archivio &#8220;Autori&#8221;.<\/p>\n<p>\u00c8 evidente che il <a href=\"http:\/\/www.sbn.it\/opacsbn\/opac\/iccu\/free.jsp\" target=\"_blank\"><b>Servizio Bibliotecario Nazionale<\/b>\u00a0(SBN)<\/a>\u00a0sia un valido amico per scrivere la tesi. Gi\u00e0 la testa \u00e8 piena di ansie e paure, dover poi cercare un ago nel pagliaio non \u00e8 davvero semplice.<br \/>\nLa vera vostra amica nella formazione, per\u00f2, \u00e8 l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>. Imparate a conoscerla sempre di pi\u00f9 leggendo il sito ufficiale o i post del\u00a0<a title=\"BLOG UNICUSANO: universit\u00e0 telematica in presenza e telematica\" href=\"https:\/\/www.unicusano.it\/blog\">BLOG di UNICUSANO<\/a>\u00a0dove sono raccontate le tante sfaccettature di questo mondo accademico. Se, invece, le domande ce le avete voi, potete porle attraverso il form\u00a0<a title=\"UNICUSANO: maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\">https:\/\/www.unicusano.it\/contatti-universita<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se state studiando per prepararvi ad un esame o, ancora pi\u00f9 verosimilmente,...","protected":false},"author":2,"featured_media":4156,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[55,161,160],"class_list":["post-4154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento-universitario","tag-orientarsi-alluniversita","tag-scegliere-il-giusto-corso-di-laurea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizio Bibliotecario Nazionale<\/title>\n<meta name=\"description\" content=\"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizio Bibliotecario Nazionale\" \/>\n<meta property=\"og:description\" content=\"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-01T04:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T14:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"219\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\"},\"headline\":\"Il Servizio Bibliotecario Nazionale? Consigliato dall\u2019UniCusano\",\"datePublished\":\"2014-04-01T04:00:34+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/servizio-bibliotecario-nazionale.jpg\",\"keywords\":[\"orientamento universitario\",\"orientarsi all'universit\u00e0\",\"scegliere il giusto corso di laurea\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/\",\"name\":\"Servizio Bibliotecario Nazionale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/servizio-bibliotecario-nazionale.jpg\",\"datePublished\":\"2014-04-01T04:00:34+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"description\":\"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/servizio-bibliotecario-nazionale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/servizio-bibliotecario-nazionale.jpg\",\"width\":390,\"height\":219,\"caption\":\"Test di orientamento dell\u2019UniCusano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizio-bibliotecario-nazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Servizio Bibliotecario Nazionale? Consigliato dall\u2019UniCusano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"description\":\"Redazione del blog di UniCusano, universit\u00e0 telematica\",\"sameAs\":[\"http:\\\/\\\/www.unicusano.it\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizio Bibliotecario Nazionale","description":"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/","og_locale":"it_IT","og_type":"article","og_title":"Servizio Bibliotecario Nazionale","og_description":"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-04-01T04:00:34+00:00","article_modified_time":"2017-04-11T14:48:30+00:00","og_image":[{"width":390,"height":219,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/"},"author":{"name":"redazione","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7"},"headline":"Il Servizio Bibliotecario Nazionale? Consigliato dall\u2019UniCusano","datePublished":"2014-04-01T04:00:34+00:00","dateModified":"2017-04-11T14:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg","keywords":["orientamento universitario","orientarsi all'universit\u00e0","scegliere il giusto corso di laurea"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/","name":"Servizio Bibliotecario Nazionale","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg","datePublished":"2014-04-01T04:00:34+00:00","dateModified":"2017-04-11T14:48:30+00:00","description":"Servizio Bibliotecario Nazionale: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla del Servizio Bibliotecario Nazionale. Leggi per scoprire tutto su quale sia il Servizio Bibliotecario Nazionale.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/03\/servizio-bibliotecario-nazionale.jpg","width":390,"height":219,"caption":"Test di orientamento dell\u2019UniCusano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizio-bibliotecario-nazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Il Servizio Bibliotecario Nazionale? Consigliato dall\u2019UniCusano"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","caption":"redazione"},"description":"Redazione del blog di UniCusano, universit\u00e0 telematica","sameAs":["http:\/\/www.unicusano.it\/blog\/"],"url":"https:\/\/www.unicusano.it\/blog\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=4154"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4154\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/4156"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=4154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=4154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=4154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}