{"id":4375,"date":"2014-04-15T06:00:43","date_gmt":"2014-04-15T04:00:43","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=4375"},"modified":"2017-04-11T16:48:30","modified_gmt":"2017-04-11T14:48:30","slug":"anticipazione-test-universitari","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/","title":{"rendered":"Anticipazione dei test universitari? Non sorprende l\u2019UniCusano"},"content":{"rendered":"<p><b>Quando scoppia la tempesta si evidenzia ancor di pi\u00f9 chi resta in piedi nella bufera. E\u2019 il caso della recentissima anticipazione dei test universitari che sta coinvolgendo migliaia di ragazzi sballottolati qua e l\u00e0 da un ennesimo episodio di cattiva comunicazione. Le informazioni su questa anticipazione dei test universitari, infatti, si rincorrono in modo discontinuo e fare il punto della situazione non \u00e8 facile. Cosa c\u2019entra l\u2019UniCusano? Come pu\u00f2 delinearsi ancor di pi\u00f9 la sua natura formativa in questa situazione? Per avere queste risposte e capire, quindi, come si intreccia l\u2019anticipazione dei test universitari, vi baster\u00e0 continuare a leggere.<!--more--><\/b><\/p>\n<p><b>\u00a0<\/b>Gi\u00e0 \u00e8 difficile capire dove va il futuro in questi anni. Se poi ci si aggiunge un\u2019<b>anticipazione<\/b> dei <b>test universitari<\/b> che non \u00e8 stata comunicata a dovere, la difficolt\u00e0 degli studenti si evidenzia in modo netto. Nello specifico, tre date cambiate nel giro di pochi mesi, tre ministri con altrettante idee diverse e i giovani che sono giustamente finiti nel pallone. Questo problema dell\u2019<b>anticipazione<\/b> dei <b>test universitari<\/b> non \u00e8 piccolo perch\u00e9 riguarda ben 80 mila studenti che, secondo una prima analisi, si pu\u00f2 tradurre col fatto che quasi 6 ragazzi su 10 non sapevano dell\u2019<b>anticipazione<\/b> dei <b>test universitari <\/b>per tempo. \u00a0D\u2019altronde era il 27 dicembre quando il <a href=\"http:\/\/www.istruzione.it\" target=\"_blank\">Miur<\/a>\u00a0ha comunicato le date ufficiali e cio\u00e8 in un periodo dell\u2019anno in cui notoriamente i laureandi sono in vacanza e i fuori sede sono addirittura in viaggio. Come se il disastro di quest\u2019anno non fosse gi\u00e0 di per s\u00e9 elevato, all\u2019orizzonte si vedono nuvole ancora pi\u00f9 nere. Come, infatti, spiega la ministra attuale dell\u2019Istruzione Stefania Giannini: \u201cL\u2019<b>anticipazione<\/b> dei <b>test universitari<\/b> in primavera \u00e8 stata una decisione assunta in precedenza al mio mandato e sulla quale io non sono intervenuta. Credo per\u00f2 che la compresenza dei test e della stagione finale della scuola con l\u2019esame di maturit\u00e0 offra elementi su cui riflettere\u201d. In realt\u00e0 c\u2019\u00e8 da riflettere sul fatto che a fare le spese di tutto questo, come sempre, sono i ragazzi e le loro famiglie. E qui si inserisce l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0che, invece, getta il seme della sua offerta formativa proprio in questo buco mettendo le esigenze di chi studia al centro di tutto. Sarebbe impossibile in questa realt\u00e0 che una storia come quella dell\u2019<b>anticipazione<\/b> dei <b>test universitari<\/b> si avveri perch\u00e9 la comunicazione \u00e8 gestita in modo snello e moderno. Esiste un <a title=\"UNICUSANO: tutorship\" href=\"https:\/\/www.unicusano.it\/universita\/tutorship\">tutor<\/a>, poi, che aiuta chi \u00e8 in difficolt\u00e0 nel suo iter formativo e che, per rimanere in questo caso, si sarebbe sincerato che il suo assistito avesse colto le novit\u00e0. Non solo. L\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0offre un <a title=\"UNICUSANO: orientamento universitario\" href=\"https:\/\/www.unicusano.it\/servizi\/orientamento-universitario\">test d\u2019orientamento<\/a>\u00a0che serve a dare i giovani l\u2019idea delle loro attitudini ma, soprattutto, che \u00e8 fruibile quando si vuole, senza dover aspettare dictat dall\u2019alto. Lo si pu\u00f2 trovare sul sito ufficiale ma anche raccontato attraverso i tanti post \u00a0del <a title=\"BLOG UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\/blog\">BLOG di UNICUSANO<\/a>. Una faccenda come questa dell\u2019<b>anticipazione<\/b> dei <b>test universitari<\/b> all\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0sarebbe, infine, impossibile perch\u00e9 c\u2019\u00e8 anche l\u2019opportunit\u00e0 di richiedere tutte le informazioni che si vuole attraverso l\u2019apposito form <a title=\"UNICUSANO: maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\">https:\/\/www.unicusano.it\/contatti-universita<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando scoppia la tempesta si evidenzia ancor di pi\u00f9 chi resta...","protected":false},"author":2,"featured_media":4377,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[55,161,160],"class_list":["post-4375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento-universitario","tag-orientarsi-alluniversita","tag-scegliere-il-giusto-corso-di-laurea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anticipazione test universitari<\/title>\n<meta name=\"description\" content=\"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anticipazione test universitari\" \/>\n<meta property=\"og:description\" content=\"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-15T04:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T14:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\"},\"headline\":\"Anticipazione dei test universitari? Non sorprende l\u2019UniCusano\",\"datePublished\":\"2014-04-15T04:00:43+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/anticipazione-test-universitari.jpg\",\"keywords\":[\"orientamento universitario\",\"orientarsi all'universit\u00e0\",\"scegliere il giusto corso di laurea\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/\",\"name\":\"Anticipazione test universitari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/anticipazione-test-universitari.jpg\",\"datePublished\":\"2014-04-15T04:00:43+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"description\":\"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/anticipazione-test-universitari.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/anticipazione-test-universitari.jpg\",\"width\":390,\"height\":240,\"caption\":\"L\u2019offerta formativa dell\u2019UniCusano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/anticipazione-test-universitari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anticipazione dei test universitari? Non sorprende l\u2019UniCusano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"description\":\"Redazione del blog di UniCusano, universit\u00e0 telematica\",\"sameAs\":[\"http:\\\/\\\/www.unicusano.it\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anticipazione test universitari","description":"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/","og_locale":"it_IT","og_type":"article","og_title":"Anticipazione test universitari","og_description":"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-04-15T04:00:43+00:00","article_modified_time":"2017-04-11T14:48:30+00:00","og_image":[{"width":390,"height":240,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/"},"author":{"name":"redazione","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7"},"headline":"Anticipazione dei test universitari? Non sorprende l\u2019UniCusano","datePublished":"2014-04-15T04:00:43+00:00","dateModified":"2017-04-11T14:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg","keywords":["orientamento universitario","orientarsi all'universit\u00e0","scegliere il giusto corso di laurea"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/","name":"Anticipazione test universitari","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg","datePublished":"2014-04-15T04:00:43+00:00","dateModified":"2017-04-11T14:48:30+00:00","description":"Anticipazione test\u00ac universitari: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dell\u2019anticipazione test\u00ac universitari. Leggi per scoprire tutto sull\u2019anticipazione dei test universitari.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/anticipazione-test-universitari.jpg","width":390,"height":240,"caption":"L\u2019offerta formativa dell\u2019UniCusano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/anticipazione-test-universitari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Anticipazione dei test universitari? Non sorprende l\u2019UniCusano"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","caption":"redazione"},"description":"Redazione del blog di UniCusano, universit\u00e0 telematica","sameAs":["http:\/\/www.unicusano.it\/blog\/"],"url":"https:\/\/www.unicusano.it\/blog\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=4375"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4375\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/4377"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=4375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=4375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=4375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}