{"id":4382,"date":"2014-04-17T06:00:35","date_gmt":"2014-04-17T04:00:35","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=4382"},"modified":"2017-04-11T16:48:30","modified_gmt":"2017-04-11T14:48:30","slug":"prospettive-lauree-online","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/","title":{"rendered":"Le prospettive ci sono per le lauree online? Solo UniCusano"},"content":{"rendered":"<p><b>Quello della formazione accademica \u00e8 un settore in continuo fermento. Da una parte la crisi ha ampliato la necessit\u00e0 di sapersi vendere con pi\u00f9 charme sul mercato del lavoro asfittico mentre dall\u2019altra ha un po\u2019 sfiduciato tutti quelli che vedono quanto un titolo di studi non sia pi\u00f9 garanzia di nulla. Le prospettive delle lauree online, per\u00f2, non sono cos\u00ec negative ma anzi risultano rosee anche e soprattutto a causa di brutte notizie che arrivano dagli Stati Uniti. Come \u00e8 possibile questo paradosso? Se volete scoprire perch\u00e9 le prospettive delle lauree online non stiano messe cos\u00ec male, continuate a leggere.<img decoding=\"async\" title=\"Continua...\" alt=\"\" data-src=\"https:\/\/www.unicusano.it\/blog\/wp-includes\/js\/tinymce\/plugins\/wordpress\/img\/trans.gif\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><!--more--><\/b><\/p>\n<p>Ciclicamente ci si chiede quali siano le <b>prospettive <\/b>delle<b> lauree online<\/b> e le risposte sono le pi\u00f9 disparate. Ultimamente, per\u00f2, con buona pace dei detrattori (che non sono pochi) sembra che il vento abbia iniziato a tirare in poppa anche e soprattutto grazie ad un fenomeno negativo che \u00e8 partito (come molte altre cose) dagli Usa. Si tratta dell\u2019<a href=\"http:\/\/www.tesionline.it\/default\/tesi.asp?idt=11808\" target=\"_blank\"><b>Overeducation<\/b><\/a>\u00a0che si verifica quando il titolo di studio che si ha non \u00e8 necessario per coprire il posto di lavoro al quale ci si candida in quanto richiedente minori competenze. Detta in parole pi\u00f9 povere, \u00e8 il tecnicismo attraverso cui si spiega, per esempio, perch\u00e9 il 15% dei tassisti\u00a0 a stelle e strisce sia laureato. Si tratta di un\u2019onda anomala che presto si abbatter\u00e0 sull\u2019Italia e che, quindi, vale la pena di studiare per tempo. Ecco qualche numero che la racconta meglio e che aiuta a dipanare la matassa delle <b>prospettive <\/b>delle<b> lauree online<\/b>: negli Stati Uniti la disoccupazione tra i laureati \u00e8 del 3,2% e, nel caso dei diplomati, arriva fino al 6,5% mentre per chi non ha preso neanche un titolo di studio sfora addirittura il 10%. Mediamente, poi, studiare ad un college costa alle famiglie americane 160 mila dollari per un ritorno esiguo, considerato che, tra gli over 25 con un contratto a tempo pieno,\u00a0i laureati guadagnano pi\u00f9 o meno il doppio rispetto ai diplomati\u00a0(1219$ a settimana contro 648$). Va da s\u00e9 che quello che racconta questo trend \u00e8 che siamo in un vicolo cieco in cui la laurea \u00e8 inutile ma sarebbe da pazzi non averla. E qui entrano in gioco le <b>prospettive <\/b>delle<b> lauree online<\/b>. Perch\u00e9 la via d\u2019uscita a questo vicolo cieco \u00e8 prendersi il \u201cpezzo di carta\u201d senza per\u00f2 depauperarsi troppo. Come non notare, quindi, che, in fatto di <b>prospettive <\/b>delle<b> lauree online<\/b>, l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0ha precorso i tempi diventando in Italia un baluardo dell\u2019<a href=\"http:\/\/www.tesionline.it\/default\/tesi.asp?idt=11808\" target=\"_blank\"><b>Overeducation<\/b><\/a>? Il costo della retta dell\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>, infatti, include tutto, compresi i materiali didattici, e questo posiziona l\u2019ateneo su una fascia molto pi\u00f9 bassa delle universit\u00e0 tradizionali che comportano anche spese di vitto e alloggio per i fuori sede. Se avete dubbi sulle <b>prospettive <\/b>delle<b> lauree online<\/b>, insomma, non dovete far altro che affidare il vostro futuro all\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>. Sempre informandovi day by day tramite il sito ufficiale e il <a title=\"BLOG UNICUSANO: universit\u00e0 telematica e in presenza\" href=\"https:\/\/www.unicusano.it\/blog\">BLOG di UNICUSANO<\/a><span style=\"color: #000000;\"><b>\u00a0<\/b>o<\/span>, in alternativa, cliccando su <a title=\"UNICUSANO: maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\">https:\/\/www.unicusano.it\/contatti-universita<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quello della formazione accademica \u00e8 un settore in continuo fermento....","protected":false},"author":2,"featured_media":4383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[55,161,160],"class_list":["post-4382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento-universitario","tag-orientarsi-alluniversita","tag-scegliere-il-giusto-corso-di-laurea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prospettive delle lauree online<\/title>\n<meta name=\"description\" content=\"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prospettive delle lauree online\" \/>\n<meta property=\"og:description\" content=\"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-17T04:00:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-11T14:48:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\"},\"headline\":\"Le prospettive ci sono per le lauree online? Solo UniCusano\",\"datePublished\":\"2014-04-17T04:00:35+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/\"},\"wordCount\":495,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/prospettive-lauree-online-.jpg\",\"keywords\":[\"orientamento universitario\",\"orientarsi all'universit\u00e0\",\"scegliere il giusto corso di laurea\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/\",\"name\":\"Prospettive delle lauree online\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/prospettive-lauree-online-.jpg\",\"datePublished\":\"2014-04-17T04:00:35+00:00\",\"dateModified\":\"2017-04-11T14:48:30+00:00\",\"description\":\"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/prospettive-lauree-online-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/prospettive-lauree-online-.jpg\",\"width\":390,\"height\":390,\"caption\":\"Scegliere la giusta universit\u00e0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-lauree-online\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le prospettive ci sono per le lauree online? Solo UniCusano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"description\":\"Redazione del blog di UniCusano, universit\u00e0 telematica\",\"sameAs\":[\"http:\\\/\\\/www.unicusano.it\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prospettive delle lauree online","description":"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/","og_locale":"it_IT","og_type":"article","og_title":"Prospettive delle lauree online","og_description":"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-04-17T04:00:35+00:00","article_modified_time":"2017-04-11T14:48:30+00:00","og_image":[{"width":390,"height":390,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/"},"author":{"name":"redazione","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7"},"headline":"Le prospettive ci sono per le lauree online? Solo UniCusano","datePublished":"2014-04-17T04:00:35+00:00","dateModified":"2017-04-11T14:48:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/"},"wordCount":495,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg","keywords":["orientamento universitario","orientarsi all'universit\u00e0","scegliere il giusto corso di laurea"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/","name":"Prospettive delle lauree online","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg","datePublished":"2014-04-17T04:00:35+00:00","dateModified":"2017-04-11T14:48:30+00:00","description":"Prospettive delle lauree online: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive delle lauree online. Leggi per scoprire tutto sulle prospettive delle lauree online.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/04\/prospettive-lauree-online-.jpg","width":390,"height":390,"caption":"Scegliere la giusta universit\u00e0"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-lauree-online\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Le prospettive ci sono per le lauree online? Solo UniCusano"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","caption":"redazione"},"description":"Redazione del blog di UniCusano, universit\u00e0 telematica","sameAs":["http:\/\/www.unicusano.it\/blog\/"],"url":"https:\/\/www.unicusano.it\/blog\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=4382"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/4382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/4383"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=4382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=4382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=4382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}