{"id":7976,"date":"2014-12-09T06:00:04","date_gmt":"2014-12-09T05:00:04","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=7976"},"modified":"2014-12-02T18:06:09","modified_gmt":"2014-12-02T17:06:09","slug":"servizi-residenza-unicusano","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/","title":{"rendered":"Tutto sui servizi della Residenza dell\u2019UniCusano"},"content":{"rendered":"<p><b>Vi ricordate quelle divertenti commedie americane ambientate nei college? Esagerazioni comiche a parte, mostravano una vita dello studente dove la qualit\u00e0 era molto alta grazie al fatto di poter rimanere costantemente sul territorio delle lezioni e in contatto con i propri colleghi. Tutto questo da noi era pura fiction, fino ad ora. Perch\u00e9 l\u2019UniCusano, nel suo costante procedimento di crescita, ha sviluppato un lato fisico in aggiunta a quella telematico dove esiste un campus universitario e tutta una serie di servizi di questa Residenza UniCusano. Curiosi? Ecco cosa c\u2019\u00e8 da sapere sui servizi della Residenza UniCusano.<!--more--><\/b><\/p>\n<p>Cosa c\u2019\u00e8 di pi\u00f9 bello della citt\u00e0 eterna? Viverla senza subirne le limitazioni. Ecco perch\u00e9 l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0ha deciso di darsi \u201cun corpo\u201d non nel modo tradizionale italiano ma seguendo la scia luminosa dei parenti a stelle strisce. Ha creato, al netto di ogni allegoria, un vero e proprio <a title=\"BLOG UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\/blog\/didattica\/corsi\/campus_universitario\/\">campus universitario<\/a>\u00a0sullo stile di quegli americani e l\u2019ha strutturato seguendo la sua mission di dare peso principalmente alle esigenze degli studenti. Ecco qual \u00e8 il terreno da cui cresce l\u2019albero dei <a title=\"UNICUSANO: servizi Residenza dell'UniCusano\" href=\"https:\/\/www.unicusano.it\/universita\/la-residenza-unicusano\"><b>servizi<\/b> della <b>Residenza<\/b> dell\u2019<b>UniCusano<\/b><\/a>. Se siete ancora nel limbo di vita in cui dovete decidere dove portare il vostro futuro, vi conviene analizzare per bene la lista che sta per seguire queste parole. Ecco l\u2019elenco dettagliato dei <a title=\"UNICUSANO: servizi Residenza dell'UniCusano\" href=\"https:\/\/www.unicusano.it\/universita\/la-residenza-unicusano\"><b>servizi<\/b>\u00a0della\u00a0<b>Residenza<\/b>\u00a0dell\u2019<b>UniCusano<\/b><\/a>:<\/p>\n<ul>\n<li>fornitura di biancheria da camera, soggetta a cambio periodico (esclusa la biancheria da bagno)<\/li>\n<li>pulizia della camera giornaliera (escluso riordino del letto)<\/li>\n<li>utenze (energia elettrica, riscaldamento, acqua)<\/li>\n<li>utilizzo degli spazi comuni<\/li>\n<li>vigilanza notturna<\/li>\n<li>ampi spazi esterni in gran parte costituiti da spazi verdi<\/li>\n<li>accesso internet wi-fi<\/li>\n<li>servizio lavanderia su richiesta<\/li>\n<\/ul>\n<p>Non solo. Tutti i giorni, dal luned\u00ec alla domenica, sono serviti la colazione, il pranzo e la cena presso la mensa dell&#8217;Universit\u00e0 ai seguenti prezzi:<\/p>\n<ul>\n<li>colazione \u20ac 1,00 (cornetto e cappuccino)<\/li>\n<li>pranzo \u20ac 5,00<\/li>\n<li>cena \u20ac 5,00<\/li>\n<\/ul>\n<p>A scorrere col dito tutti i <a title=\"UNICUSANO: servizi Residenza dell'UniCusano\" href=\"https:\/\/www.unicusano.it\/universita\/la-residenza-unicusano\"><b>servizi<\/b>\u00a0della\u00a0<b>Residenza<\/b>\u00a0dell\u2019<b>UniCusano<\/b><\/a>\u00a0si ha ancora la sensazione di vivere in un film americano ma \u00e8 la pura realt\u00e0. Lo potete constatare \u00a0\u00a0\u00a0\u00a0da soli dal sito ufficiale, dal <a title=\"BLOG dell'UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\/blog\">BLOG dell\u2019UNICUSANO<\/a>\u00a0o dall\u2019apposito form informativo <a title=\"UNICUSANO: maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\">https:\/\/www.unicusano.it\/contatti-universita<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vi ricordate quelle divertenti commedie americane ambientate nei...","protected":false},"author":2,"featured_media":7977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[55,161,160],"class_list":["post-7976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento-universitario","tag-orientarsi-alluniversita","tag-scegliere-il-giusto-corso-di-laurea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi della Residenza dell\u2019UniCusano<\/title>\n<meta name=\"description\" content=\"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi della Residenza dell\u2019UniCusano\" \/>\n<meta property=\"og:description\" content=\"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-09T05:00:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\"},\"headline\":\"Tutto sui servizi della Residenza dell\u2019UniCusano\",\"datePublished\":\"2014-12-09T05:00:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/\"},\"wordCount\":360,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/servizi-residenza-unicusano-.jpg\",\"keywords\":[\"orientamento universitario\",\"orientarsi all'universit\u00e0\",\"scegliere il giusto corso di laurea\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/\",\"name\":\"Servizi della Residenza dell\u2019UniCusano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/servizi-residenza-unicusano-.jpg\",\"datePublished\":\"2014-12-09T05:00:04+00:00\",\"description\":\"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/servizi-residenza-unicusano-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/servizi-residenza-unicusano-.jpg\",\"width\":400,\"height\":268,\"caption\":\"Servizi della Residenza dell\u2019UniCusano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/servizi-residenza-unicusano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tutto sui servizi della Residenza dell\u2019UniCusano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"description\":\"Redazione del blog di UniCusano, universit\u00e0 telematica\",\"sameAs\":[\"http:\\\/\\\/www.unicusano.it\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi della Residenza dell\u2019UniCusano","description":"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/","og_locale":"it_IT","og_type":"article","og_title":"Servizi della Residenza dell\u2019UniCusano","og_description":"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-12-09T05:00:04+00:00","og_image":[{"width":400,"height":268,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/"},"author":{"name":"redazione","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7"},"headline":"Tutto sui servizi della Residenza dell\u2019UniCusano","datePublished":"2014-12-09T05:00:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/"},"wordCount":360,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg","keywords":["orientamento universitario","orientarsi all'universit\u00e0","scegliere il giusto corso di laurea"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/","name":"Servizi della Residenza dell\u2019UniCusano","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg","datePublished":"2014-12-09T05:00:04+00:00","description":"Servizi della Residenza dell\u2019UniCusano: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla dei servizi della Residenza dell\u2019UniCusano. Leggi per scoprire tutto sui servizi della Residenza dell\u2019UniCusano.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/servizi-residenza-unicusano-.jpg","width":400,"height":268,"caption":"Servizi della Residenza dell\u2019UniCusano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/servizi-residenza-unicusano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Tutto sui servizi della Residenza dell\u2019UniCusano"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","caption":"redazione"},"description":"Redazione del blog di UniCusano, universit\u00e0 telematica","sameAs":["http:\/\/www.unicusano.it\/blog\/"],"url":"https:\/\/www.unicusano.it\/blog\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/7976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=7976"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/7976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/7977"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=7976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=7976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=7976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}