{"id":8077,"date":"2014-12-16T06:00:51","date_gmt":"2014-12-16T05:00:51","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=8077"},"modified":"2014-12-09T18:39:05","modified_gmt":"2014-12-09T17:39:05","slug":"prospettive-elearning","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/","title":{"rendered":"UniCusano e prospettive dell\u2019eLearning"},"content":{"rendered":"<p><b>Chi non guarda oltre \u00e8 perso. Perch\u00e9 ormai il mondo del lavoro \u00e8 diventato una partita a scacchi e l\u2019unico modo di avere la meglio \u00e8 saper prevedere le mosse dell\u2019avversario. Ecco perch\u00e9 diventa molto utile analizzare e comprendere le prospettive dell\u2019eLearning in Italia e, soprattutto, come si legano all\u2019UniCusano. Cos\u00ec, mentre i detrattori sono impegnati a gettar fango senza una logica e i distratti a rovinarsi la vita con scelte che non hanno pi\u00f9 ragione d\u2019essere al giorno d\u2019oggi, voi, che ben sapete quali siano le prospettive dell\u2019eLearning, potete marciare a spron battuto verso un futuro degno di essere chiamato cos\u00ec.<!--more--><\/b><\/p>\n<p>A prescindere da quel che sostiene un certo tipo di stampa un po\u2019 tradizionalista, le <b>prospettive <\/b>dell\u2019<b>eLearning<\/b> sono davvero molto rosee. Capirne la ragione vi consentir\u00e0 di capire anche perch\u00e9 vi conviene valutare l\u2019offerta didattica dell\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>. Il primo punto che chiarisce bene le <b>prospettive <\/b>dell\u2019<b>eLearning<\/b> \u00e8 che il mondo del lavoro \u00e8 in continuo fermento. Dopo anni di stasi, infatti, le cose mutano ogni giorno ed \u00e8 fondamentale star dietro al ciclone con una formazione modulare e dinamica che non risulti vecchia ed inutile per le aziende. Altro punto che si annoda alle <b>prospettive <\/b>dell\u2019<b>eLearning<\/b> \u00e8 la tecnologia. \u00c8 ormai impensabile farne a meno, ancor pi\u00f9 per i nativi digitali, eppure stenta ad apparire nei materiali didattici a disposizione. Attrezzature come il <a title=\"BLOG UNICUSANO: WiFi gratis\" href=\"https:\/\/www.unicusano.it\/blog\/didattica\/nuove-tecnologie-didattiche\/wifi_gratis\/\">WiFi gratis<\/a>\u00a0e le <a title=\"BLOG UNICUSANO: LIM\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/lim\/\">LIM<\/a>, infatti, sono all\u2019ordine del giorno all\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>\u00a0ma un po\u2019 meno altrove. La terza ragione per cui sono \u201cmesse bene\u201d le <b>prospettive <\/b>dell\u2019<b>eLearning<\/b> \u00e8 che il mondo va sempre pi\u00f9 verso un migliore accesso all\u2019istruzione. Come dimostra l\u2019<a title=\"UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\">UniCusano<\/a>, la FAD (formazione a distanza) azzera certi costi di spostamento e affini e consente alle universit\u00e0 di essere pi\u00f9 competitive sui prezzi dei corsi di laurea dove sono compresi anche i libri di testo. Tra convenzioni e borse di studio, in sintesi, sono davvero pochi quelli che ad oggi non si possono permettere di studiare con un click. In ultima analisi, le <b>prospettive <\/b>dell\u2019<b>eLearning<\/b> sono destinate a crescere anche perch\u00e9 le istituzioni, fino ad ora un po\u2019 caute sul tema, si stanno pian piano accorgendo che il fenomeno non \u00e8 un fenomeno ma un\u2019evoluzione. Ne \u00e8 esempio la\u00a0Open Universities Australia, un consorzio di tredici scuole con un mix di corsi di laurea e post-laurea, tutti a distanza.<br \/>\nIl miglior modo di intuire le <b>prospettive <\/b>dell\u2019<b>eLearning<\/b>, comunque, \u00e8 leggere il sito ufficiale o, ancor meglio, il <a title=\"BLOG UNICUSANO: universit\u00e0 in presenza e telematica\" href=\"https:\/\/www.unicusano.it\/blog\">BLOG di UNICUSANO<\/a>. Potete anche stabilire un contatto diretto attraverso questo apposito form <a title=\"UNICUSANO: maggiori informazioni\" href=\"https:\/\/www.unicusano.it\/contatti-universita\">https:\/\/www.unicusano.it\/contatti-universita<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi non guarda oltre \u00e8 perso. Perch\u00e9 ormai il mondo del lavoro...","protected":false},"author":2,"featured_media":8078,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[55,161,160],"class_list":["post-8077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-orientamento-universitario","tag-orientarsi-alluniversita","tag-scegliere-il-giusto-corso-di-laurea"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prospettive dell\u2019eLearning<\/title>\n<meta name=\"description\" content=\"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prospettive dell\u2019eLearning\" \/>\n<meta property=\"og:description\" content=\"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-16T05:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"329\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/\"},\"author\":{\"name\":\"redazione\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\"},\"headline\":\"UniCusano e prospettive dell\u2019eLearning\",\"datePublished\":\"2014-12-16T05:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/\"},\"wordCount\":433,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/prospettive-elearning.jpg\",\"keywords\":[\"orientamento universitario\",\"orientarsi all'universit\u00e0\",\"scegliere il giusto corso di laurea\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/\",\"name\":\"Prospettive dell\u2019eLearning\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/prospettive-elearning.jpg\",\"datePublished\":\"2014-12-16T05:00:51+00:00\",\"description\":\"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/prospettive-elearning.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/prospettive-elearning.jpg\",\"width\":400,\"height\":329,\"caption\":\"Prospettive dell\u2019eLearning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/prospettive-elearning\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UniCusano e prospettive dell\u2019eLearning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/f674e0388bddd2c972cf8df1244713f7\",\"name\":\"redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g\",\"caption\":\"redazione\"},\"description\":\"Redazione del blog di UniCusano, universit\u00e0 telematica\",\"sameAs\":[\"http:\\\/\\\/www.unicusano.it\\\/blog\\\/\"],\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/luca\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prospettive dell\u2019eLearning","description":"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/","og_locale":"it_IT","og_type":"article","og_title":"Prospettive dell\u2019eLearning","og_description":"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2014-12-16T05:00:51+00:00","og_image":[{"width":400,"height":329,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg","type":"image\/jpeg"}],"author":"redazione","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/"},"author":{"name":"redazione","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7"},"headline":"UniCusano e prospettive dell\u2019eLearning","datePublished":"2014-12-16T05:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/"},"wordCount":433,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg","keywords":["orientamento universitario","orientarsi all'universit\u00e0","scegliere il giusto corso di laurea"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/","name":"Prospettive dell\u2019eLearning","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg","datePublished":"2014-12-16T05:00:51+00:00","description":"Prospettive dell\u2019eLearning: ecco l\u2019articolo del blog ufficiale dell\u2019universit\u00e0 UniCusano che parla delle prospettive dell\u2019eLearning. Leggi per scoprire tutto sulle prospettive dell\u2019eLearning.","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2014\/12\/prospettive-elearning.jpg","width":400,"height":329,"caption":"Prospettive dell\u2019eLearning"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/prospettive-elearning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"UniCusano e prospettive dell\u2019eLearning"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/f674e0388bddd2c972cf8df1244713f7","name":"redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771bd177b879ffc3a1c7c0c6a1d03b33dbe9ecc5613bfdab118b361683acba3a?s=96&d=mm&r=g","caption":"redazione"},"description":"Redazione del blog di UniCusano, universit\u00e0 telematica","sameAs":["http:\/\/www.unicusano.it\/blog\/"],"url":"https:\/\/www.unicusano.it\/blog\/author\/luca\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/8077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=8077"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/8077\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/8078"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=8077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=8077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=8077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}