{"id":8786,"date":"2015-01-29T08:30:24","date_gmt":"2015-01-29T07:30:24","guid":{"rendered":"http:\/\/www.unicusano.it\/blog\/?p=8786"},"modified":"2015-01-29T08:30:24","modified_gmt":"2015-01-29T07:30:24","slug":"sport-unicusano","status":"publish","type":"post","link":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/","title":{"rendered":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale"},"content":{"rendered":"<p>Una giornata particolare quella di oggi per gli studenti dell\u2019Universit\u00e0 Niccol\u00f2 Cusano e per i giocatori della Unicusano Fondi Calcio, la squadra della ricerca scientifica italiana, che si incontreranno nel campus dell\u2019Ateneo (Via Don Carlo Gnocchi 3 \u2013 Roma).<\/p>\n<p>Quello di oggi, infatti, sar\u00e0 un gioved\u00ec universitario per i calciatori della formazione entrata a far parte della famiglia della Cusano nel novembre scorso: in mattinata la squadra rossobl\u00f9, con staff tecnico e dirigenziale al gran completo, sar\u00e0 in visita alla Cusano per incontrare i professori e gli studenti dell&#8217;Ateneo capitolino.<\/p>\n<p>Si prospetta, dunque, una giornata di festa e di condivisione, che render\u00e0 ancora pi\u00f9 forte il legame tra la realt\u00e0 accademica e la squadra di calcio, da quest\u2019anno unite nel nome della ricerca scientifica. Alle ore 10.30 avverr\u00e0 la presentazione della squadra nell\u2019Aula Magna dell\u2019Ateneo, dove a fare gli onori di casa ci saranno il Magnifico Rettore, Professor Fabio Fortuna, e il Dott. Stefano Ranucci, Presidente del CDA dell&#8217;Universit\u00e0 Niccol\u00f2 Cusano. Saliranno con loro, sul palco, il capitano della squadra, Giuseppe Rinaldi e il pi\u00f9 giovane della rosa a disposizione di Mister Pochesci, Andrea Avallone, promettente attaccante, classe 1997.<\/p>\n<p>Questo splendido abbraccio tra sport e conoscenza sar\u00e0 una importante occasione per mostrare agli studenti dell\u2019Universit\u00e0 Niccol\u00f2 Cusano e agli atleti dell\u2019Unicusano Fondi Calcio il nuovo laboratorio di ricerca per la Valutazione Funzionale motoria e sportiva della Cusano, un\u2019importante branca della Scienza dello Sport in grado di fornire preziose indicazioni sia agli atleti professionisti che a tutti coloro che vogliono migliorare forma fisica e qualit\u00e0 della propria vita.<\/p>\n<p>I test utilizzati consentono la rilevazione dei parametri psicologici o fisiologici dell\u2019organismo. All&#8217;interno del nuovo laboratorio di ricerca scientifica che si trova nel campus dell&#8217;Universit\u00e0 Niccol\u00f2 Cusano, si possono analizzare quindi i fattori della prestazione, studiare le componenti aerobiche e anaerobiche, stilare programmi di allenamento e percorsi specifici di screening e valutazione per atleti e persone comuni, dare consigli dal punto di vista nutrizionale, seguire e monitorare la condizione dei pi\u00f9 giovani sollecitando, ad esempio, programmi di prevenzione dell\u2019obesit\u00e0 infantile. Tra i primi atleti che verranno sottoposti ai test nel nuovo laboratorio della Cusano ci saranno naturalmente tutti i giocatori dell\u2019Unicusano Fondi Calcio, gi\u00e0 da domani stesso. I test forniranno ai preparatori e ai fisioterapisti che curano il benessere della squadra informazioni utilissime\u00a0 per veicolare il lavoro su ogni singolo atleta.<\/p>\n<p>Il laboratorio che verr\u00e0 inaugurato oggi all&#8217;interno del campus dell&#8217;Universit\u00e0 Niccol\u00f2 Cusano, inoltre,\u00a0 servir\u00e0 per le attivit\u00e0 di tirocinio curriculare degli studenti dei Corsi di Laurea in Scienze dell\u2019Educazione e della Formazione e Scienze Psicologiche. Questi all&#8217;interno del laboratorio avranno modo di trovare un cardiofrequenzimetro a lettura telemetrica multipla e relativo software di analisi, un metabolimetro, un adipometro, un lattacidrometro, un lettino massaggi, una bilancia a colonna e un biofeedback.<\/p>\n<p>Al termine del pranzo con gli studenti che avverr\u00e0 nella mensa dell\u2019ateneo, la giornata capitolina dell\u2019Unicusano Fondi Calcio proseguir\u00e0 al \u201cFulvio Bernardini\u201d di Trigoria per un interessante test amichevole (inizio alle ore 15) con la squadra Allievi Nazionali della Roma, diretta da Federico Coppitelli, capolista del proprio girone. &#8220;Una partita sicuramente interessante, ed anche una bella occasione per i nostri tanti giovani&#8221; ha affermato l\u2019allenatore dell\u2019Unicusano Fondi Calcio, Sandro Pochesci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una giornata particolare quella di oggi per gli studenti dell\u2019Universit\u00e0...","protected":false},"author":5,"featured_media":8787,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[902,875,173],"class_list":["post-8786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-laboratori","tag-unicusano-fondi","tag-universita-niccolo-cusano"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale<\/title>\n<meta name=\"description\" content=\"Oggi l&#039;Unicusano Fondi far\u00e0 visita agli studenti dell&#039;Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale\" \/>\n<meta property=\"og:description\" content=\"Oggi l&#039;Unicusano Fondi far\u00e0 visita agli studenti dell&#039;Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/universita.unicusano\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-29T07:30:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"987\" \/>\n\t<meta property=\"og:image:height\" content=\"692\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roberto Arduini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@unicusano\" \/>\n<meta name=\"twitter:site\" content=\"@unicusano\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Arduini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/\"},\"author\":{\"name\":\"Roberto Arduini\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\"},\"headline\":\"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale\",\"datePublished\":\"2015-01-29T07:30:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg\",\"keywords\":[\"Laboratori\",\"unicusano fondi\",\"universit\u00e0 niccol\u00f2 cusano\"],\"articleSection\":[\"Universit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/\",\"name\":\"L'Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg\",\"datePublished\":\"2015-01-29T07:30:24+00:00\",\"description\":\"Oggi l'Unicusano Fondi far\u00e0 visita agli studenti dell'Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg\",\"width\":987,\"height\":692,\"caption\":\"Oggi l'Universit\u00e0 Niccol\u00f2 Cusano inaugurer\u00e0 un nuovo importante laboratorio in occasione della visita al campus dell'Unicusano Fondi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/universita\\\/sport-unicusano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"name\":\"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#organization\",\"name\":\"Universit\u00e0 Niccol\u00f2 Cusano\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"contentUrl\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/logo-blog-unicusano.png\",\"width\":218,\"height\":130,\"caption\":\"Universit\u00e0 Niccol\u00f2 Cusano\"},\"image\":{\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/universita.unicusano\\\/\",\"https:\\\/\\\/x.com\\\/unicusano\",\"https:\\\/\\\/www.instagram.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/2539786\",\"https:\\\/\\\/www.pinterest.com\\\/unicusano\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/younicusano\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/#\\\/schema\\\/person\\\/28cd477b229ff1994b39dd4400c2649c\",\"name\":\"Roberto Arduini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g\",\"caption\":\"Roberto Arduini\"},\"url\":\"https:\\\/\\\/www.unicusano.it\\\/blog\\\/author\\\/roberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale","description":"Oggi l'Unicusano Fondi far\u00e0 visita agli studenti dell'Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/","og_locale":"it_IT","og_type":"article","og_title":"L'Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale","og_description":"Oggi l'Unicusano Fondi far\u00e0 visita agli studenti dell'Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio","og_url":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/","og_site_name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","article_publisher":"https:\/\/www.facebook.com\/universita.unicusano\/","article_published_time":"2015-01-29T07:30:24+00:00","og_image":[{"width":987,"height":692,"url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg","type":"image\/jpeg"}],"author":"Roberto Arduini","twitter_card":"summary_large_image","twitter_creator":"@unicusano","twitter_site":"@unicusano","twitter_misc":{"Scritto da":"Roberto Arduini","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#article","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/"},"author":{"name":"Roberto Arduini","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c"},"headline":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale","datePublished":"2015-01-29T07:30:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg","keywords":["Laboratori","unicusano fondi","universit\u00e0 niccol\u00f2 cusano"],"articleSection":["Universit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/","url":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/","name":"L'Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale","isPartOf":{"@id":"https:\/\/www.unicusano.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#primaryimage"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg","datePublished":"2015-01-29T07:30:24+00:00","description":"Oggi l'Unicusano Fondi far\u00e0 visita agli studenti dell'Universit\u00e0 Niccol\u00f2 Cusano. Studenti e calciatori pranzeranno insieme. Oggi verr\u00e0 anche inaugurato un importante laboratorio","breadcrumb":{"@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#primaryimage","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2015\/01\/unicusano-fondi-visita-la-sede-della-universit\u00e0-niccol\u00f2-cusano.jpg","width":987,"height":692,"caption":"Oggi l'Universit\u00e0 Niccol\u00f2 Cusano inaugurer\u00e0 un nuovo importante laboratorio in occasione della visita al campus dell'Unicusano Fondi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.unicusano.it\/blog\/universita\/sport-unicusano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unicusano.it\/blog\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Universit\u00e0 Niccol\u00f2 Cusano abbraccia lo sport: oggi giornata speciale"}]},{"@type":"WebSite","@id":"https:\/\/www.unicusano.it\/blog\/#website","url":"https:\/\/www.unicusano.it\/blog\/","name":"Blog dell&#039;Universit\u00e0 Niccol\u00f2 Cusano","description":"","publisher":{"@id":"https:\/\/www.unicusano.it\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unicusano.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.unicusano.it\/blog\/#organization","name":"Universit\u00e0 Niccol\u00f2 Cusano","url":"https:\/\/www.unicusano.it\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","contentUrl":"https:\/\/www.unicusano.it\/blog\/wp-content\/uploads\/2017\/04\/logo-blog-unicusano.png","width":218,"height":130,"caption":"Universit\u00e0 Niccol\u00f2 Cusano"},"image":{"@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/universita.unicusano\/","https:\/\/x.com\/unicusano","https:\/\/www.instagram.com\/unicusano\/","https:\/\/www.linkedin.com\/school\/2539786","https:\/\/www.pinterest.com\/unicusano\/","https:\/\/www.youtube.com\/user\/younicusano"]},{"@type":"Person","@id":"https:\/\/www.unicusano.it\/blog\/#\/schema\/person\/28cd477b229ff1994b39dd4400c2649c","name":"Roberto Arduini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aac418ddc0197dde293bd63538b0a7ae2562bba65abf78d929f844d92b56c9f5?s=96&d=mm&r=g","caption":"Roberto Arduini"},"url":"https:\/\/www.unicusano.it\/blog\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/8786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/comments?post=8786"}],"version-history":[{"count":0,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/posts\/8786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media\/8787"}],"wp:attachment":[{"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/media?parent=8786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/categories?post=8786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unicusano.it\/blog\/wp-json\/wp\/v2\/tags?post=8786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}